{"id":11803,"date":"2026-06-14T18:24:23","date_gmt":"2026-06-14T18:24:23","guid":{"rendered":"https:\/\/fhacademia.com\/courses\/environmental-protection-loss-prevention-and-pollution-control\/"},"modified":"2026-06-14T18:24:23","modified_gmt":"2026-06-14T18:24:23","slug":"environmental-protection-loss-prevention-and-pollution-control","status":"publish","type":"courses","link":"https:\/\/fhacademia.com\/ar\/courses\/environmental-protection-loss-prevention-and-pollution-control\/","title":{"rendered":"Environmental Protection: Loss Prevention and Pollution Control"},"content":{"rendered":"<p>Environmental Protection: Loss Prevention and Pollution Control<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Professional training course by Fusion Harbour.<\/p>\n","protected":false},"featured_media":0,"template":"","course-catigory":[89],"class_list":["post-11803","courses","type-courses","status-publish","hentry","course-catigory-health-safety"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Environmental Protection: Loss Prevention and Pollution Control - Fusion Harbour Academia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fhacademia.com\/courses\/environmental-protection-loss-prevention-and-pollution-control\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Environmental Protection: Loss Prevention and Pollution Control - Fusion Harbour Academia\" \/>\n<meta property=\"og:description\" content=\"Professional training course by Fusion Harbour.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fhacademia.com\/courses\/environmental-protection-loss-prevention-and-pollution-control\/\" \/>\n<meta property=\"og:site_name\" content=\"Fusion Harbour Academia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fhacademia.com\\\/courses\\\/environmental-protection-loss-prevention-and-pollution-control\\\/\",\"url\":\"https:\\\/\\\/fhacademia.com\\\/courses\\\/environmental-protection-loss-prevention-and-pollution-control\\\/\",\"name\":\"Environmental Protection: Loss Prevention and Pollution Control - Fusion Harbour Academia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fhacademia.com\\\/#website\"},\"datePublished\":\"2026-06-14T18:24:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fhacademia.com\\\/courses\\\/environmental-protection-loss-prevention-and-pollution-control\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fhacademia.com\\\/courses\\\/environmental-protection-loss-prevention-and-pollution-control\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fhacademia.com\\\/courses\\\/environmental-protection-loss-prevention-and-pollution-control\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fhacademia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Courses\",\"item\":\"https:\\\/\\\/fhacademia.com\\\/courses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Environmental Protection: Loss Prevention and Pollution Control\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fhacademia.com\\\/#website\",\"url\":\"https:\\\/\\\/fhacademia.com\\\/\",\"name\":\"Fusion Harbour Academia\",\"description\":\"Training &amp; Consultancy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fhacademia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Environmental Protection: Loss Prevention and Pollution Control - Fusion Harbour Academia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fhacademia.com\/courses\/environmental-protection-loss-prevention-and-pollution-control\/","og_locale":"ar_AR","og_type":"article","og_title":"Environmental Protection: Loss Prevention and Pollution Control - Fusion Harbour Academia","og_description":"Professional training course by Fusion Harbour.","og_url":"https:\/\/fhacademia.com\/courses\/environmental-protection-loss-prevention-and-pollution-control\/","og_site_name":"Fusion Harbour Academia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fhacademia.com\/courses\/environmental-protection-loss-prevention-and-pollution-control\/","url":"https:\/\/fhacademia.com\/courses\/environmental-protection-loss-prevention-and-pollution-control\/","name":"Environmental Protection: Loss Prevention and Pollution Control - Fusion Harbour Academia","isPartOf":{"@id":"https:\/\/fhacademia.com\/#website"},"datePublished":"2026-06-14T18:24:23+00:00","breadcrumb":{"@id":"https:\/\/fhacademia.com\/courses\/environmental-protection-loss-prevention-and-pollution-control\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fhacademia.com\/courses\/environmental-protection-loss-prevention-and-pollution-control\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fhacademia.com\/courses\/environmental-protection-loss-prevention-and-pollution-control\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fhacademia.com\/"},{"@type":"ListItem","position":2,"name":"Courses","item":"https:\/\/fhacademia.com\/courses\/"},{"@type":"ListItem","position":3,"name":"Environmental Protection: Loss Prevention and Pollution Control"}]},{"@type":"WebSite","@id":"https:\/\/fhacademia.com\/#website","url":"https:\/\/fhacademia.com\/","name":"Fusion Harbour Academia","description":"Training &amp; Consultancy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fhacademia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"_links":{"self":[{"href":"https:\/\/fhacademia.com\/ar\/wp-json\/wp\/v2\/courses\/11803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fhacademia.com\/ar\/wp-json\/wp\/v2\/courses"}],"about":[{"href":"https:\/\/fhacademia.com\/ar\/wp-json\/wp\/v2\/types\/courses"}],"wp:attachment":[{"href":"https:\/\/fhacademia.com\/ar\/wp-json\/wp\/v2\/media?parent=11803"}],"wp:term":[{"taxonomy":"course-catigory","embeddable":true,"href":"https:\/\/fhacademia.com\/ar\/wp-json\/wp\/v2\/course-catigory?post=11803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}