{"id":13701,"date":"2026-06-14T18:30:44","date_gmt":"2026-06-14T18:30:44","guid":{"rendered":"https:\/\/fhacademia.com\/courses\/safety-in-analytical-laboratory-training\/"},"modified":"2026-06-14T18:30:44","modified_gmt":"2026-06-14T18:30:44","slug":"safety-in-analytical-laboratory-training","status":"publish","type":"courses","link":"https:\/\/fhacademia.com\/ar\/courses\/safety-in-analytical-laboratory-training\/","title":{"rendered":"Safety in Analytical Laboratory Training"},"content":{"rendered":"<p>Safety in Analytical Laboratory Training<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Professional training course by Fusion Harbour.<\/p>\n","protected":false},"featured_media":0,"template":"","course-catigory":[96],"class_list":["post-13701","courses","type-courses","status-publish","hentry","course-catigory-laboratory"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Safety in Analytical Laboratory Training - Fusion Harbour Academia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fhacademia.com\/ar\/courses\/safety-in-analytical-laboratory-training\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Safety in Analytical Laboratory Training - Fusion Harbour Academia\" \/>\n<meta property=\"og:description\" content=\"Professional training course by Fusion Harbour.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fhacademia.com\/ar\/courses\/safety-in-analytical-laboratory-training\/\" \/>\n<meta property=\"og:site_name\" content=\"Fusion Harbour Academia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fhacademia.com\\\/ar\\\/courses\\\/safety-in-analytical-laboratory-training\\\/\",\"url\":\"https:\\\/\\\/fhacademia.com\\\/ar\\\/courses\\\/safety-in-analytical-laboratory-training\\\/\",\"name\":\"Safety in Analytical Laboratory Training - Fusion Harbour Academia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fhacademia.com\\\/#website\"},\"datePublished\":\"2026-06-14T18:30:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fhacademia.com\\\/ar\\\/courses\\\/safety-in-analytical-laboratory-training\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fhacademia.com\\\/ar\\\/courses\\\/safety-in-analytical-laboratory-training\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fhacademia.com\\\/ar\\\/courses\\\/safety-in-analytical-laboratory-training\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fhacademia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Courses\",\"item\":\"https:\\\/\\\/fhacademia.com\\\/courses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Safety in Analytical Laboratory Training\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fhacademia.com\\\/#website\",\"url\":\"https:\\\/\\\/fhacademia.com\\\/\",\"name\":\"Fusion Harbour Academia\",\"description\":\"Training &amp; Consultancy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fhacademia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Safety in Analytical Laboratory Training - Fusion Harbour Academia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fhacademia.com\/ar\/courses\/safety-in-analytical-laboratory-training\/","og_locale":"ar_AR","og_type":"article","og_title":"Safety in Analytical Laboratory Training - Fusion Harbour Academia","og_description":"Professional training course by Fusion Harbour.","og_url":"https:\/\/fhacademia.com\/ar\/courses\/safety-in-analytical-laboratory-training\/","og_site_name":"Fusion Harbour Academia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fhacademia.com\/ar\/courses\/safety-in-analytical-laboratory-training\/","url":"https:\/\/fhacademia.com\/ar\/courses\/safety-in-analytical-laboratory-training\/","name":"Safety in Analytical Laboratory Training - Fusion Harbour Academia","isPartOf":{"@id":"https:\/\/fhacademia.com\/#website"},"datePublished":"2026-06-14T18:30:44+00:00","breadcrumb":{"@id":"https:\/\/fhacademia.com\/ar\/courses\/safety-in-analytical-laboratory-training\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fhacademia.com\/ar\/courses\/safety-in-analytical-laboratory-training\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fhacademia.com\/ar\/courses\/safety-in-analytical-laboratory-training\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fhacademia.com\/"},{"@type":"ListItem","position":2,"name":"Courses","item":"https:\/\/fhacademia.com\/courses\/"},{"@type":"ListItem","position":3,"name":"Safety in Analytical Laboratory Training"}]},{"@type":"WebSite","@id":"https:\/\/fhacademia.com\/#website","url":"https:\/\/fhacademia.com\/","name":"Fusion Harbour Academia","description":"Training &amp; Consultancy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fhacademia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"_links":{"self":[{"href":"https:\/\/fhacademia.com\/ar\/wp-json\/wp\/v2\/courses\/13701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fhacademia.com\/ar\/wp-json\/wp\/v2\/courses"}],"about":[{"href":"https:\/\/fhacademia.com\/ar\/wp-json\/wp\/v2\/types\/courses"}],"wp:attachment":[{"href":"https:\/\/fhacademia.com\/ar\/wp-json\/wp\/v2\/media?parent=13701"}],"wp:term":[{"taxonomy":"course-catigory","embeddable":true,"href":"https:\/\/fhacademia.com\/ar\/wp-json\/wp\/v2\/course-catigory?post=13701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}